{"id":28381,"date":"2017-07-25T05:47:00","date_gmt":"2017-07-25T10:47:00","guid":{"rendered":"https:\/\/www.mpechicago.com\/enfriamiento-genuino-a-traves-del-agua-en-rodillos-munones-y-cojinetes\/"},"modified":"2025-05-01T23:38:28","modified_gmt":"2025-05-02T04:38:28","slug":"enfriamiento-genuino-a-traves-del-agua-en-rodillos-munones-y-cojinetes","status":"publish","type":"post","link":"https:\/\/www.mpechicago.com\/es\/enfriamiento-genuino-a-traves-del-agua-en-rodillos-munones-y-cojinetes\/","title":{"rendered":"Enfriamiento genuino a trav\u00e9s del agua en rodillos, mu\u00f1ones y cojinetes"},"content":{"rendered":"\n<p>Una luz brilla a trav\u00e9s de un rodillo instalado en un granulador de la serie IMD para demostrar el enfriamiento genuino a trav\u00e9s del agua de los granuladores MPE. Los mu\u00f1ones del rodillo est\u00e1n montados dentro de los cojinetes, donde pronto se agregar\u00e1n accesorios de agua en ambos extremos. Este dise\u00f1o garantiza la estabilidad de la temperatura en todos los rodillos, mu\u00f1ones y cojinetes para un mejor funcionamiento y una mayor vida \u00fatil de los componentes. <\/p>\n\n<p>Los rodillos granuladores, los mu\u00f1ones y los cojinetes est\u00e1n dise\u00f1ados para el rectificado de precisi\u00f3n en grandes vol\u00famenes. Con aplicaciones que requieren distribuciones de part\u00edculas ajustadas y espacios entre rollos tan peque\u00f1os como 50 micras, la estabilizaci\u00f3n de las tolerancias y el control de la temperatura pueden marcar la diferencia entre un excelente producto de caf\u00e9 y uno inferior. <\/p>\n\n<p>El calor altera las tolerancias y contribuye a un desgaste mec\u00e1nico m\u00e1s r\u00e1pido. El calor en un solo rodamiento puede alterar la paralelidad de los rodillos y alterar significativamente la distribuci\u00f3n de part\u00edculas y reducir la precisi\u00f3n general. <\/p>\n\n<p>Para controlar el calor de los componentes, uno de los dise\u00f1os de ingenier\u00eda caracter\u00edsticos de MPE son los rodillos genuinos refrigerados por agua que se encuentran en la mayor\u00eda de los modelos IMD. La idea es simple; El agua corre a trav\u00e9s de ambos juegos de cojinetes y mu\u00f1ones, y rodillos, por supuesto, para que permanezcan a una temperatura constante durante el funcionamiento. Este<strong> enfriamiento de doble cara<\/strong> mantiene los rodillos en perfecto funcionamiento paralelo y reduce el desgaste de los componentes.  <\/p>\n\n<p>Los dise\u00f1os de refrigeraci\u00f3n por agua que se ven en los molinillos de caf\u00e9 industriales de la competencia suelen ser <strong>unilaterales.<\/strong> Y si bien esto puede enfriar adecuadamente los rodillos y evitar un segundo tostado no deseado del caf\u00e9, los cojinetes no enfriados en el otro lado son susceptibles de un mayor desgaste relacionado con el calor y la expansi\u00f3n metal\u00fargica que conduce a una p\u00e9rdida de paralelismo de los rodillos. Esta p\u00e9rdida da como resultado una molienda menos precisa y, en consecuencia, un producto de caf\u00e9 molido de menor calidad. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una luz brilla a trav\u00e9s de un rodillo instalado en un granulador de la serie IMD para demostrar el enfriamiento genuino a trav\u00e9s del agua del granulador MPE<\/p>\n","protected":false},"author":20,"featured_media":19361,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","footnotes":""},"categories":[141],"tags":[],"posttype":[331],"resourcetype":[],"class_list":["post-28381","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cafe","posttype-case-study-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Enfriamiento genuino a trav\u00e9s del agua en rodillos, mu\u00f1ones y cojinetes - Equipos de proceso modernos<\/title>\n<meta name=\"description\" content=\"Descubra soluciones genuinas de enfriamiento por agua para rodillos, mu\u00f1ones y rodamientos. Explore equipos confiables.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mpechicago.com\/es\/enfriamiento-genuino-a-traves-del-agua-en-rodillos-munones-y-cojinetes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Enfriamiento genuino a trav\u00e9s del agua en rodillos, mu\u00f1ones y cojinetes - Equipos de proceso modernos\" \/>\n<meta property=\"og:description\" content=\"Descubra soluciones genuinas de enfriamiento por agua para rodillos, mu\u00f1ones y rodamientos. Explore equipos confiables.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mpechicago.com\/es\/enfriamiento-genuino-a-traves-del-agua-en-rodillos-munones-y-cojinetes\/\" \/>\n<meta property=\"og:site_name\" content=\"Equipos de proceso modernos\" \/>\n<meta property=\"article:published_time\" content=\"2017-07-25T10:47:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-02T04:38:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mpechicago.com\/wp-content\/uploads\/2017\/07\/Iron-man-rolls.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1004\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cyberoptik\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cyberoptik\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mpechicago.com\\\/es\\\/enfriamiento-genuino-a-traves-del-agua-en-rodillos-munones-y-cojinetes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mpechicago.com\\\/es\\\/enfriamiento-genuino-a-traves-del-agua-en-rodillos-munones-y-cojinetes\\\/\"},\"author\":{\"name\":\"Cyberoptik\",\"@id\":\"https:\\\/\\\/www.mpechicago.com\\\/es\\\/#\\\/schema\\\/person\\\/95739544654293e431b080d65b94b71b\"},\"headline\":\"Enfriamiento genuino a trav\u00e9s del agua en rodillos, mu\u00f1ones y cojinetes\",\"datePublished\":\"2017-07-25T10:47:00+00:00\",\"dateModified\":\"2025-05-02T04:38:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mpechicago.com\\\/es\\\/enfriamiento-genuino-a-traves-del-agua-en-rodillos-munones-y-cojinetes\\\/\"},\"wordCount\":391,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.mpechicago.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mpechicago.com\\\/es\\\/enfriamiento-genuino-a-traves-del-agua-en-rodillos-munones-y-cojinetes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mpechicago.com\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/Iron-man-rolls.jpg\",\"articleSection\":[\"Caf\u00e9\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.mpechicago.com\\\/es\\\/enfriamiento-genuino-a-traves-del-agua-en-rodillos-munones-y-cojinetes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mpechicago.com\\\/es\\\/enfriamiento-genuino-a-traves-del-agua-en-rodillos-munones-y-cojinetes\\\/\",\"url\":\"https:\\\/\\\/www.mpechicago.com\\\/es\\\/enfriamiento-genuino-a-traves-del-agua-en-rodillos-munones-y-cojinetes\\\/\",\"name\":\"Enfriamiento genuino a trav\u00e9s del agua en rodillos, mu\u00f1ones y cojinetes - Equipos de proceso modernos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mpechicago.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mpechicago.com\\\/es\\\/enfriamiento-genuino-a-traves-del-agua-en-rodillos-munones-y-cojinetes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mpechicago.com\\\/es\\\/enfriamiento-genuino-a-traves-del-agua-en-rodillos-munones-y-cojinetes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mpechicago.com\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/Iron-man-rolls.jpg\",\"datePublished\":\"2017-07-25T10:47:00+00:00\",\"dateModified\":\"2025-05-02T04:38:28+00:00\",\"description\":\"Descubra soluciones genuinas de enfriamiento por agua para rodillos, mu\u00f1ones y rodamientos. Explore equipos confiables.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mpechicago.com\\\/es\\\/enfriamiento-genuino-a-traves-del-agua-en-rodillos-munones-y-cojinetes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mpechicago.com\\\/es\\\/enfriamiento-genuino-a-traves-del-agua-en-rodillos-munones-y-cojinetes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mpechicago.com\\\/es\\\/enfriamiento-genuino-a-traves-del-agua-en-rodillos-munones-y-cojinetes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mpechicago.com\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/Iron-man-rolls.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mpechicago.com\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/Iron-man-rolls.jpg\",\"width\":1500,\"height\":1004},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mpechicago.com\\\/es\\\/enfriamiento-genuino-a-traves-del-agua-en-rodillos-munones-y-cojinetes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hogar\",\"item\":\"https:\\\/\\\/www.mpechicago.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Enfriamiento genuino a trav\u00e9s del agua en rodillos, mu\u00f1ones y cojinetes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mpechicago.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.mpechicago.com\\\/es\\\/\",\"name\":\"Equipos de proceso modernos\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mpechicago.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mpechicago.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mpechicago.com\\\/es\\\/#organization\",\"name\":\"Equipos de proceso modernos\",\"url\":\"https:\\\/\\\/www.mpechicago.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mpechicago.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mpechicago.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/www.mpechicago.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/logo.png\",\"width\":200,\"height\":91,\"caption\":\"Equipos de proceso modernos\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mpechicago.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mpechicago.com\\\/es\\\/#\\\/schema\\\/person\\\/95739544654293e431b080d65b94b71b\",\"name\":\"Cyberoptik\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c82a339bf1cba52be26f422645e5119f5fbe70eec85894d237d9a957f55e9586?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c82a339bf1cba52be26f422645e5119f5fbe70eec85894d237d9a957f55e9586?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c82a339bf1cba52be26f422645e5119f5fbe70eec85894d237d9a957f55e9586?s=96&d=mm&r=g\",\"caption\":\"Cyberoptik\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Enfriamiento genuino a trav\u00e9s del agua en rodillos, mu\u00f1ones y cojinetes - Equipos de proceso modernos","description":"Descubra soluciones genuinas de enfriamiento por agua para rodillos, mu\u00f1ones y rodamientos. Explore equipos confiables.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mpechicago.com\/es\/enfriamiento-genuino-a-traves-del-agua-en-rodillos-munones-y-cojinetes\/","og_locale":"es_ES","og_type":"article","og_title":"Enfriamiento genuino a trav\u00e9s del agua en rodillos, mu\u00f1ones y cojinetes - Equipos de proceso modernos","og_description":"Descubra soluciones genuinas de enfriamiento por agua para rodillos, mu\u00f1ones y rodamientos. Explore equipos confiables.","og_url":"https:\/\/www.mpechicago.com\/es\/enfriamiento-genuino-a-traves-del-agua-en-rodillos-munones-y-cojinetes\/","og_site_name":"Equipos de proceso modernos","article_published_time":"2017-07-25T10:47:00+00:00","article_modified_time":"2025-05-02T04:38:28+00:00","og_image":[{"width":1500,"height":1004,"url":"https:\/\/www.mpechicago.com\/wp-content\/uploads\/2017\/07\/Iron-man-rolls.jpg","type":"image\/jpeg"}],"author":"Cyberoptik","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Cyberoptik","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mpechicago.com\/es\/enfriamiento-genuino-a-traves-del-agua-en-rodillos-munones-y-cojinetes\/#article","isPartOf":{"@id":"https:\/\/www.mpechicago.com\/es\/enfriamiento-genuino-a-traves-del-agua-en-rodillos-munones-y-cojinetes\/"},"author":{"name":"Cyberoptik","@id":"https:\/\/www.mpechicago.com\/es\/#\/schema\/person\/95739544654293e431b080d65b94b71b"},"headline":"Enfriamiento genuino a trav\u00e9s del agua en rodillos, mu\u00f1ones y cojinetes","datePublished":"2017-07-25T10:47:00+00:00","dateModified":"2025-05-02T04:38:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mpechicago.com\/es\/enfriamiento-genuino-a-traves-del-agua-en-rodillos-munones-y-cojinetes\/"},"wordCount":391,"commentCount":0,"publisher":{"@id":"https:\/\/www.mpechicago.com\/es\/#organization"},"image":{"@id":"https:\/\/www.mpechicago.com\/es\/enfriamiento-genuino-a-traves-del-agua-en-rodillos-munones-y-cojinetes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mpechicago.com\/wp-content\/uploads\/2017\/07\/Iron-man-rolls.jpg","articleSection":["Caf\u00e9"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.mpechicago.com\/es\/enfriamiento-genuino-a-traves-del-agua-en-rodillos-munones-y-cojinetes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.mpechicago.com\/es\/enfriamiento-genuino-a-traves-del-agua-en-rodillos-munones-y-cojinetes\/","url":"https:\/\/www.mpechicago.com\/es\/enfriamiento-genuino-a-traves-del-agua-en-rodillos-munones-y-cojinetes\/","name":"Enfriamiento genuino a trav\u00e9s del agua en rodillos, mu\u00f1ones y cojinetes - Equipos de proceso modernos","isPartOf":{"@id":"https:\/\/www.mpechicago.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mpechicago.com\/es\/enfriamiento-genuino-a-traves-del-agua-en-rodillos-munones-y-cojinetes\/#primaryimage"},"image":{"@id":"https:\/\/www.mpechicago.com\/es\/enfriamiento-genuino-a-traves-del-agua-en-rodillos-munones-y-cojinetes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mpechicago.com\/wp-content\/uploads\/2017\/07\/Iron-man-rolls.jpg","datePublished":"2017-07-25T10:47:00+00:00","dateModified":"2025-05-02T04:38:28+00:00","description":"Descubra soluciones genuinas de enfriamiento por agua para rodillos, mu\u00f1ones y rodamientos. Explore equipos confiables.","breadcrumb":{"@id":"https:\/\/www.mpechicago.com\/es\/enfriamiento-genuino-a-traves-del-agua-en-rodillos-munones-y-cojinetes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mpechicago.com\/es\/enfriamiento-genuino-a-traves-del-agua-en-rodillos-munones-y-cojinetes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mpechicago.com\/es\/enfriamiento-genuino-a-traves-del-agua-en-rodillos-munones-y-cojinetes\/#primaryimage","url":"https:\/\/www.mpechicago.com\/wp-content\/uploads\/2017\/07\/Iron-man-rolls.jpg","contentUrl":"https:\/\/www.mpechicago.com\/wp-content\/uploads\/2017\/07\/Iron-man-rolls.jpg","width":1500,"height":1004},{"@type":"BreadcrumbList","@id":"https:\/\/www.mpechicago.com\/es\/enfriamiento-genuino-a-traves-del-agua-en-rodillos-munones-y-cojinetes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hogar","item":"https:\/\/www.mpechicago.com\/es\/"},{"@type":"ListItem","position":2,"name":"Enfriamiento genuino a trav\u00e9s del agua en rodillos, mu\u00f1ones y cojinetes"}]},{"@type":"WebSite","@id":"https:\/\/www.mpechicago.com\/es\/#website","url":"https:\/\/www.mpechicago.com\/es\/","name":"Equipos de proceso modernos","description":"","publisher":{"@id":"https:\/\/www.mpechicago.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mpechicago.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.mpechicago.com\/es\/#organization","name":"Equipos de proceso modernos","url":"https:\/\/www.mpechicago.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mpechicago.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.mpechicago.com\/wp-content\/uploads\/2019\/12\/logo.png","contentUrl":"https:\/\/www.mpechicago.com\/wp-content\/uploads\/2019\/12\/logo.png","width":200,"height":91,"caption":"Equipos de proceso modernos"},"image":{"@id":"https:\/\/www.mpechicago.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.mpechicago.com\/es\/#\/schema\/person\/95739544654293e431b080d65b94b71b","name":"Cyberoptik","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c82a339bf1cba52be26f422645e5119f5fbe70eec85894d237d9a957f55e9586?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c82a339bf1cba52be26f422645e5119f5fbe70eec85894d237d9a957f55e9586?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c82a339bf1cba52be26f422645e5119f5fbe70eec85894d237d9a957f55e9586?s=96&d=mm&r=g","caption":"Cyberoptik"}}]}},"_links":{"self":[{"href":"https:\/\/www.mpechicago.com\/es\/wp-json\/wp\/v2\/posts\/28381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mpechicago.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mpechicago.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mpechicago.com\/es\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mpechicago.com\/es\/wp-json\/wp\/v2\/comments?post=28381"}],"version-history":[{"count":1,"href":"https:\/\/www.mpechicago.com\/es\/wp-json\/wp\/v2\/posts\/28381\/revisions"}],"predecessor-version":[{"id":28382,"href":"https:\/\/www.mpechicago.com\/es\/wp-json\/wp\/v2\/posts\/28381\/revisions\/28382"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mpechicago.com\/es\/wp-json\/wp\/v2\/media\/19361"}],"wp:attachment":[{"href":"https:\/\/www.mpechicago.com\/es\/wp-json\/wp\/v2\/media?parent=28381"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mpechicago.com\/es\/wp-json\/wp\/v2\/categories?post=28381"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mpechicago.com\/es\/wp-json\/wp\/v2\/tags?post=28381"},{"taxonomy":"posttype","embeddable":true,"href":"https:\/\/www.mpechicago.com\/es\/wp-json\/wp\/v2\/posttype?post=28381"},{"taxonomy":"resourcetype","embeddable":true,"href":"https:\/\/www.mpechicago.com\/es\/wp-json\/wp\/v2\/resourcetype?post=28381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}